{"id":840,"date":"2018-07-12T11:09:46","date_gmt":"2018-07-12T09:09:46","guid":{"rendered":"http:\/\/abbatia.eu\/?p=840"},"modified":"2018-07-12T11:09:46","modified_gmt":"2018-07-12T09:09:46","slug":"programmation-estivale-de-labbaye-de-letoile","status":"publish","type":"post","link":"http:\/\/abbatia.eu\/index.php\/2018\/07\/12\/programmation-estivale-de-labbaye-de-letoile\/","title":{"rendered":"Programmation estivale de l&rsquo;Abbaye de l&rsquo;Etoile"},"content":{"rendered":"<p>Voici le programme des animations pour l&rsquo;Abbaye de l&rsquo;Etoile :<\/p>\n<p>\u00a0\u00bb Respiration\u00a0\u00bb<br \/>\nL&rsquo;artiste Dominique Maroille expose a l&rsquo;abbaye<br \/>\nDes sculptures qui racontent le souffle du vent qui se pose \u00e0 l\u2019int\u00e9rieur de l&rsquo;\u00eatre ; la libert\u00e9 et le lien ; les secrets murmur\u00e9s par les peupliers ; l&rsquo;oiseau et le sable ; et le parfum de l\u2019oc\u00e9an.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-841 size-medium\" src=\"http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/affiche-final-expo-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" \/><br \/>\nVendredi 20 juillet 21h, \u00a0soir\u00e9e cont\u00e9e \u00a0\u00ab \u00a0Belles plantes \u00bb, racont\u00e9e champ\u00eatre et dr\u00f4le entre deux femmes au caract\u00e8re bien tremp\u00e9 pour une d\u00e9couverte des plantes et de leurs usages.<br \/>\nMise en lumi\u00e8re de l\u2019abbaye.<br \/>\nSoir\u00e9e r\u00e9alis\u00e9e avec la participation active de la compagnie Globtrott.<br \/>\nTarif : 6\u20ac \u00a0Gratuit \u2013 12 ans<br \/>\nR\u00e9servation 05.49.21.05.47<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-842 aligncenter\" src=\"http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/belles-plantes-217x300.jpg\" alt=\"\" width=\"217\" height=\"300\" \/><br \/>\nDimanche 22 juillet 16 h, \u00a0\u00ab balade au temps du moyen \u00e2ge \u00bb, chants, musique et initiation \u00e0 la danse m\u00e9di\u00e9vale. Un moment convivial gr\u00e2ce \u00e0 la bonne humeur de l&rsquo;association \u00ab\u00a0la salamandre\u00a0\u00bb.<br \/>\nTarifs : 10\u20ac \u00a0\u00a0Gratuit &#8211; de 14 ans \u00a0\u00a05 \u20ac \u00e9tudiants et demandeurs d\u2019emploi<br \/>\nR\u00e9servation 05.49.21.05.47<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-843 aligncenter\" src=\"http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/balade-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" \/><br \/>\n25 juillet ,1er et 22 ao\u00fbt<br \/>\nEntrez dans \u00ab \u00a0le livre sacr\u00e9 \u00bb<br \/>\nPrendre sa besace et partir \u00e0 la rencontre de Petit Pierre, novice \u00e0 l\u2019Abbaye de l\u2019Etoile, r\u00e9soudre des \u00e9nigmes, d\u00e9couvrir la l\u00e9gende des pierres, endosser le costume des moines\u2026<br \/>\nUne exp\u00e9rience in\u00e9dite \u00e0 vivre en famille<br \/>\nA partir de 6 ans<br \/>\n6\u20ac par enfant, gratuit pour les accompagnants dans la limite de 2 personnes<br \/>\nAdulte suppl\u00e9mentaire 5\u20ac (prix d\u2019une visite libre)<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-844 aligncenter\" src=\"http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-300x225.jpg 300w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-768x576.jpg 768w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-1024x768.jpg 1024w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-830x623.jpg 830w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-230x173.jpg 230w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-350x263.jpg 350w, http:\/\/abbatia.eu\/wp-content\/uploads\/2018\/07\/IMG_8470-480x360.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voici le programme des animations pour l&rsquo;Abbaye de l&rsquo;Etoile : \u00a0\u00bb Respiration\u00a0\u00bb [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-840","post","type-post","status-publish","format-standard","hentry","category-1"],"_links":{"self":[{"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/posts\/840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/comments?post=840"}],"version-history":[{"count":1,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/posts\/840\/revisions"}],"predecessor-version":[{"id":845,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/posts\/840\/revisions\/845"}],"wp:attachment":[{"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/media?parent=840"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/categories?post=840"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/abbatia.eu\/index.php\/wp-json\/wp\/v2\/tags?post=840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}